{"id":1883,"date":"2018-09-07T19:23:51","date_gmt":"2018-09-07T19:23:51","guid":{"rendered":"http:\/\/amadalamazigh.press.ma\/fr\/?p=1883"},"modified":"2018-09-07T19:23:51","modified_gmt":"2018-09-07T19:23:51","slug":"rabat-accueille-le-15e-congres-panafricaine-darcheologie-et-de-prehistoire","status":"publish","type":"post","link":"https:\/\/amadalamazigh.press.ma\/fr\/rabat-accueille-le-15e-congres-panafricaine-darcheologie-et-de-prehistoire\/","title":{"rendered":"Rabat accueille le 15e Congr\u00e8s PanAfricaine d\u2019Arch\u00e9ologie et de Pr\u00e9histoire"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1884 alignleft\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa-172x250.jpg?resize=172%2C250\" alt=\"\" width=\"172\" height=\"250\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?resize=172%2C250&amp;ssl=1 172w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?w=660&amp;ssl=1 660w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" \/>L\u2019Universit\u00e9 Mohammed\u00a0V\u00a0de Rabat en partenariat avec\u00a0l\u2019Institut National des Sciences d\u2019Arch\u00e9ologie et du Patrimoine, l\u2019Universit\u00e9 Mohammed 1er d\u2019Oujda, et l\u2019Universit\u00e9 Moulay Ismail de Mekn\u00e8s, organise le XVe Congr\u00e8s de l\u2019Association PanAfricaine d\u2019Arch\u00e9ologie, de Pr\u00e9histoire et Disciplines Associ\u00e9es, qui se tiendra \u00e0 Rabat, du 10 au 14 Septembre 2018. A l\u2019Universit\u00e9 Mohamed V, Facult\u00e9 des Sciences, sous th\u00e8me\u00a0\u00abValorisation du patrimoine culturel africain et D\u00e9veloppement durable\u00bb.<\/p>\n<p>D\u2019apr\u00e8s le communiqu\u00e9 du comit\u00e9 d\u2019organisation, ce congr\u00e8s panafricain visera en particulier \u00e0\u00a0\u00abconstruire des ponts de communication et de coop\u00e9ration entre les pays africains et soutenir des programmes de recherche conjoints entre les diff\u00e9rentes institutions de recherche africaines, et aussi pour renforcer le r\u00f4le et la place de l\u2019arch\u00e9ologie en tant que levier de d\u00e9veloppement r\u00e9gional et socio-\u00e9conomique et en faire un vecteur de d\u00e9veloppement durable\u00bb<\/p>\n<p>Ainsi que ce congr\u00e8s fait appel \u00e0 \u00abplus de 400 participants d\u2019Afrique et d\u2019autre continents repr\u00e9sentant diff\u00e9rents domaines; des chercheurs universitaires, responsable des secteurs culturels et arch\u00e9ologiques, experts internationaux, de plus de 50 pays\u00bb.<\/p>\n<p>Selon les organisateurs, \u00abLes membres de la soci\u00e9t\u00e9 Panafricaine d\u2019 Arch\u00e9ologie, de Pr\u00e9histoire et disciplines associ\u00e9s ont \u00e9lu \u00e0 l\u2019unanimit\u00e9 le Royaume du Maroc pour accueillir son 15\u00e9me congr\u00e8s, a l\u2019attention de toutes nouvelles d\u00e9couvertes effectu\u00e9es au Maroc, \u00e0 Jebel Irhoud, o\u00f9 le plus ancien Homo Sapiens au monde vieux de 300 000 ans a vu le jour\u00bb, apr\u00e8s Nairobi, Kenya (1947), Alger, Alg\u00e9rie(1952),\u00a0 Livingstone, Zambie (1955), Kinshasa, DR. Congo(1959), Tenerife, \u00eeles Canaries (1963), Dakar, S\u00e9n\u00e9gal (1967), Addis-Abeba, Ethiopie (1971), Nairobi, Kenya (1977), Jos, Nigeria (1983), Harare, Zimbabwe (1995), Bamako, Mali (2001), Gaborone, Botswana (2005), Dakar, S\u00e9n\u00e9gal (2010), et Johannesburg, Afrique du Sud (2014).<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1884 size-full\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?resize=660%2C960\" alt=\"\" width=\"660\" height=\"960\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?w=660&amp;ssl=1 660w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?resize=172%2C250&amp;ssl=1 172w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Universit\u00e9 Mohammed\u00a0V\u00a0de Rabat en partenariat avec\u00a0l\u2019Institut National des Sciences d\u2019Arch\u00e9ologie et du Patrimoine, l\u2019Universit\u00e9 Mohammed 1er d\u2019Oujda, et l\u2019Universit\u00e9 Moulay Ismail de Mekn\u00e8s, organise le XVe Congr\u00e8s de l\u2019Association PanAfricaine d\u2019Arch\u00e9ologie, de Pr\u00e9histoire et Disciplines Associ\u00e9es, qui se tiendra \u00e0 Rabat, du 10 au 14 Septembre 2018. A l\u2019Universit\u00e9 Mohamed V, Facult\u00e9 des Sciences, sous &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1884,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26,10],"tags":[],"class_list":["post-1883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-maroc"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p9uxE2-un","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2018\/09\/pa.jpg?fit=660%2C960&ssl=1","_links":{"self":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/1883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/comments?post=1883"}],"version-history":[{"count":2,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/1883\/revisions"}],"predecessor-version":[{"id":1886,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/1883\/revisions\/1886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media\/1884"}],"wp:attachment":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media?parent=1883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/categories?post=1883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/tags?post=1883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}