{"id":3213,"date":"2020-12-09T17:44:03","date_gmt":"2020-12-09T17:44:03","guid":{"rendered":"https:\/\/amadalamazigh.press.ma\/fr\/?p=3213"},"modified":"2020-12-09T17:45:13","modified_gmt":"2020-12-09T17:45:13","slug":"monsieur-emmanuel-macron-president-de-la-republique-francaise-pourquoi-vous-acharnez-a-arabiser-et-a-deraciner-les-amazighs-de-france","status":"publish","type":"post","link":"https:\/\/amadalamazigh.press.ma\/fr\/monsieur-emmanuel-macron-president-de-la-republique-francaise-pourquoi-vous-acharnez-a-arabiser-et-a-deraciner-les-amazighs-de-france\/","title":{"rendered":"Monsieur Emmanuel MACRON, Pr\u00e9sident de la R\u00e9publique fran\u00e7aise: Pourquoi vous acharnez \u00e0 \u00ab\u00a0arabiser\u00a0\u00bb et \u00e0 d\u00e9raciner les Amazighs de France?"},"content":{"rendered":"<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3215 alignleft\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2020\/12\/MACRON_RAHA-2.jpg?resize=450%2C190&#038;ssl=1\" alt=\"\" width=\"450\" height=\"190\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2020\/12\/MACRON_RAHA-2.jpg?resize=450%2C190&amp;ssl=1 450w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2020\/12\/MACRON_RAHA-2.jpg?w=998&amp;ssl=1 998w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>Monsieur Emmanuel MACRON, Pr\u00e9sident de la R\u00e9publique fran\u00e7aise: Pourquoi vous acharnez \u00e0 \u00ab arabiser \u00bb et \u00e0 d\u00e9raciner les Amazighs de France?<\/strong><\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p><strong>Lors d\u2019une interview que vous venez de donner en direct au m\u00e9dia\u00a0<\/strong><em>Brut<\/em><strong>, ce samedi 5 d\u00e9cembre, en vous <\/strong>interrogeant sur le projet de loi sur l\u2019enseignement de la langue arabe, vous avez d\u00e9clar\u00e9, tout \u00e0 fait \u00e0 l\u2019oppos\u00e9 du v\u00f4tre discours du Mulhouse de 18 f\u00e9vrier dernier\u00a0: \u00ab\u00a0<em>On a \u00e9norm\u00e9ment de jeunes dont les familles parlent arabe, parfois les deux parents, dont la culture familiale est en arabe. Et ils apprennent dans l\u2019\u00e9cole de la R\u00e9publique le fran\u00e7ais. Ils vont perfectionner l\u2019apprentissage de leur langue maternelle ou familiale \u00e0 l\u2019ext\u00e9rieur car la R\u00e9publique leur offre peu d\u2019espaces pour cela\u00a0<\/em>\u00bb. Vous avez ajout\u00e9 que: \u00ab\u00a0<em>quand votre enfant parle arabe, c\u2019est une chance pour la France, \u00e7a a quelque chose \u00e0 apporter \u00e0 notre pays (\u2026)\u00a0<\/em>\u00bb, en vous alignant parfaitement sur les propos de M. Jack LANG, pr\u00e9sident de l\u2019Institut du Monde Arabe (IMA), qui avait affirm\u00e9 auparavant que la \u00ab\u00a0<em>langue arabe est une langue et un tr\u00e9sor de France<\/em>\u00a0\u00bb. Cependant,, ce que vos ministres, vos conseillers et votre excellence, vous ent\u00eatez \u00e0 ignorer c\u2019est que la deuxi\u00e8me langue r\u00e9ellement parl\u00e9e en France, ce n\u2019est pas la langue arabe, sinon la langue amazighe, et plus concr\u00e8tement, les variantes dialectales de cette langue, comme viennent de bien le souligner trois \u00e9minents chercheurs fran\u00e7ais, en l\u2019occurrence Tassadit YACINE, Pierre VERMEREN et Omar HAMOURIT. En effet, ces derniers ont eu le courage de souligner dans un r\u00e9cent article que \u00ab\u00a0<em>la langue maternelle des immigr\u00e9s n\u2019est pas l\u2019arabe<\/em>\u00a0\u00bb(1). Et par extension, la langue maternelle de la plupart des citoyennes et des citoyens fran\u00e7ais d\u2019origine nord-africaine est, sans aucun doute, la langue amazighe (d\u00e9j\u00e0 officielle au Maroc et en Alg\u00e9rie) et c\u2019est pr\u00e9cis\u00e9ment ce que j\u2019avais signal\u00e9 \u00e0 votre ministre de l\u2019Europe et des Affaires \u00c9trang\u00e8res lors de sa r\u00e9cente visite au Maroc. Je lui avais pr\u00e9cis\u00e9 explicitement que le fait de continuer \u00e0 ignorer les l\u00e9gitimes requ\u00eates des Amazighs, vous continuez \u00e0 d\u00e9former \u00ab<em>la v\u00e9rit\u00e9 historique\u00bb\u00a0<\/em>des pays d\u2019Afrique du Nord. De ce fait, vous continuez \u00e0<em>\u00a0<\/em>\u00a0 provoquer de l\u2019ali\u00e9nation culturelle et le d\u00e9racinement identitaire des jeunes fran\u00e7ais issus de l\u2019\u00e9migration nord-africaine, et par cons\u00e9quent, vous ent\u00eatez \u00e0 les condamner \u00e0 alimenter le radicalisme islamiste et le s\u00e9paratisme religieux. Des fl\u00e9aux \u00e0 l\u2019origine des horribles attentats terroristes dont votre pays est devenu la cible privil\u00e9gi\u00e9e et qui menacent s\u00e9rieusement la paix et la s\u00e9curit\u00e9 de l\u2019Hexagone et de celle de l\u2019Europe (2).<\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p>Votre interview nous rappelle tristement le discours de l\u2019ex-pr\u00e9sident Nicolas Sarkozy qu\u2019il avait tenu le 15 septembre 2011 \u00e0 Benghazi, lorsqu\u2019il avait affirm\u00e9 : <em>\u00ab (\u2026) jeunes de Benghazi, jeunes de Libye, jeunes Arabes (\u2026) tous les peuples \u00ab arabes \u00bb qui veulent se lib\u00e9rer de leurs cha\u00eenes \u2026\u00a0\u00bb<\/em>. Des propos qui laissent penser que le peuple libyen, comme le reste des peuples nord-africains, serait un peuple \u00abarabe\u00bb autant sur le plan ethnique qu\u2019historique, sociologique, identitaire, culturel et linguistique, alors que le succ\u00e8s de la r\u00e9volution libyenne, \u00e0 la suite du \u00ab\u00a0printemps d\u00e9mocratique des peuples\u00a0\u00bb, revient en grande partie au peuple autochtone amazigh du Jbel Nefoussa, dont la jeunesse s\u2019est rebell\u00e9 \u00e0 l\u2019Est et qui a eu le d\u00e9fi de lib\u00e9rer la capitale Tripoli.<\/p>\n<p>Toutefois, ceux que vous continuez \u00e0 consid\u00e9rer comme des \u00abArabes\u00bb ne sont, en r\u00e9alit\u00e9, que des Amazighs, que pour beaucoup se sont arabis\u00e9s apr\u00e8s leur conversion \u00e0 l\u2019Islam. Une arabisation forc\u00e9e, voulue et acc\u00e9l\u00e9r\u00e9e pour des raisons id\u00e9ologiques par les pouvoirs autoritaires \u00e0 partir des ann\u00e9es soixante-dix dont celui de feu l\u2019\u00e9gyptien Jamal Abdel Nasser et le dictateur d\u00e9chu Kadhafi.<\/p>\n<p>Une politique d\u2019arabisation \u00e0 contre-sens, que vous voulez perp\u00e9tuer sur votre territoire, bien qu\u2019il a d\u00e9j\u00e0 r\u00e9ussi \u00e0 ruiner diam\u00e9tralement le syst\u00e8me \u00e9ducatif de nos propres pays d\u2019Afrique du nord (Maroc, Alg\u00e9rie, Tunisie\u2026). Or, cette n\u00e9faste politique \u00e9ducative a \u00e9t\u00e9 enclench\u00e9e par vos propres \u00e9coles coloniales \u00abfranco-arabes\u00bb, et qui sont \u00e0 l\u2019origine du d\u00e9racinement continuel des Amazighs. Notez bien ce que confessait notre \u00e9minent amazighologue M. Mohamed CHAFIK \u00e0 propos de la dite: \u00ab\u00a0<em>Or, j\u2019estime qu\u2019en mati\u00e8re d\u2019\u00e9ducation, il y a eu une v\u00e9ritable trahison de la part d\u2019une frange de la classe politique. Je veux parler des d\u00e9fenseurs acharn\u00e9s de l\u2019arabisation de la masse d\u2019\u00e9l\u00e8ves marocains, qui ont mis leurs propres enfants dans les syst\u00e8mes \u00e9trangers. Ce n\u2019est pas tant une erreur d\u2019appr\u00e9ciation, ni une faute involontaire, comme veulent bien nous le faire comprendre certains. Non, c\u2019est vraiment un acte de trahison\u00a0\u00bb<\/em>(4). En r\u00e9alit\u00e9, c\u2019est ce que continue \u00e0 perp\u00e9tuer l\u2019actuel ministre marocain de l\u2019\u00e9ducation nationale, en bloquant l\u2019enseignement de la langue tout en envoyant ses fils suivre des cours au sein du lyc\u00e9e fran\u00e7ais Descartes de Rabat\u00a0! (5)<\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p>Il est difficile d\u2019ignorer que les troupes marocaines recrut\u00e9s et envoy\u00e9s par les autorit\u00e9s militaires du protectorat, au secours de la France, comme chairs \u00e0 canons, aux fronts de la Premi\u00e8re et de la Deuxi\u00e8me Guerres mondiales, sont dans leur \u00e9crasante majorit\u00e9 des Amazighs. Des Amazighs des montagnes du Moyen Atlas qui ont contribu\u00e9, avec leurs sueurs et leurs sangs, \u00e0 la lib\u00e9ration de la France du danger nazi, comme le refl\u00e8te merveilleusement le film \u00ab\u00a0Indig\u00e8nes\u00a0\u00bb de r\u00e9alisateur Rachid Bouchareb.<\/p>\n<p>N\u2019oubliez pas que ce sont les mains des \u00e9migr\u00e9s Amazighs des montagnes de Kabylie et de Souss qui ont contribu\u00e9 \u00e0 la reconstruction des \u00e9difices et des infrastructures de la France juste apr\u00e8s sa d\u00e9molition \u00e0 la suite de chaque guerre mondiale. Bien que le patronat fran\u00e7ais se d\u00e9pla\u00e7ait sur le terrain, pendant les ann\u00e9es cinquante et soixante, aux villages les plus recul\u00e9s des montagnes de l\u2019Atlas pour recruter la main d\u2019\u0153uvre amazighe pour redresser et d\u00e9velopper vos complexes industriels, vos usines automobiles et vos mines du nord. Savez-vous que les meilleurs vignobles d\u2019Aquitaine et d\u2019Avignon sont travaill\u00e9s avec soin par des agriculteurs amazighs des montagnes du Rif, qui ont accompagn\u00e9 leurs anciens patrons des champs oranais vers la France, juste apr\u00e8s l\u2019ind\u00e9pendance de l\u2019Alg\u00e9rie?<\/p>\n<p>Etes-vous bien conscients que vos habitations sont actuellement chauff\u00e9es par du gaz alg\u00e9rien, en territoire amazighe (et non pas au Qatar\u00a0!), et illumin\u00e9s par l\u2019\u00e9lectricit\u00e9 des centrales nucl\u00e9aires \u00e0 base d\u2019uranium extraite \u00e0 Arlit, en territoires touar\u00e8gues!<\/p>\n<p>Comme vous devriez savoir, l\u2019\u00e9conomie de la France est intimement li\u00e9e aux Amazighs et \u00e0 leurs territoires d\u2019origine, qui ne se trouvent pas du tout en Arabie, sinon en Afrique septentrionale. Cependant, savez-vous pourquoi la campagne de boycott, d\u00e9clench\u00e9e par le pr\u00e9sident turc contre vos produits, n&rsquo;a pas eu du tout de retomb\u00e9es en Afrique du Nord? Simplement parce que les millions de citoyens amazighs du Maroc, d\u2019Alg\u00e9rie, de Tunisie, de Mauritanie\u2026 sont des consommateurs privil\u00e9gi\u00e9s des produits <em>Made in France<\/em>, et qui roulent, en pr\u00e9f\u00e9rence, dans des voitures de marque fran\u00e7aise (Renault, Peugeot, Citro\u00ebn, Dacia\u2026)\u00a0!<\/p>\n<p>Monsieur Le Pr\u00e9sident,<\/p>\n<p>A l\u2019occasion de ce 72\u00e8me anniversaire de la D\u00e9claration Universelle des Droits de l\u2019Homme, vous allez vanter de nouveau que votre pays est le foyer des droits de l\u2019homme, le pays qui a chass\u00e9 la monarchie absolutiste de Louis XVI, \u00e0 la suite de votre m\u00e9morable r\u00e9volution de 1789, et qui s\u2019est dot\u00e9 de la d\u00e9claration universelle des droits du citoyen, donnant par la suite la D\u00e9claration Universelle des Droits de l\u2019Homme. Savez-vous que les Amazighs vous ont pr\u00e9c\u00e9d\u00e9 de 15 si\u00e8cles, lorsque l\u2019empereur d\u2019origine amazighe Caracalla, petit-fils de l\u2019empereur amazigho-liby\u00e9en Septimo Severo, et qui est n\u00e9, en plus, \u00e0 la ville romaine de Lugdunum lyonnaise en 188 (o\u00f9 l\u2019empereur Caligula avait assassin\u00e9, \u00e0 l\u2019\u00e9poque romaine, notre dernier roi maure Ptol\u00e9m\u00e9e, pour la simple raison qu\u2019il \u00e9tait habill\u00e9 de mani\u00e8re plus \u00e9l\u00e9gante que lui\u00a0!), a d\u00e9clench\u00e9 la premi\u00e8re r\u00e9volution citoyenne de l\u2019histoire, en d\u00e9fendant en faveur des m\u00eames droits de citoyennet\u00e9 des barbares d\u2019Europe, dont les Gaulois, et de la Mauritanie (Afrique du Nord)\u00bb avec ceux des citoyens de Rome vers 211 (6).<\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p>En d\u00e9finitive, nous vous prions de vous inviter \u00e0 rectifier votre perception envers les Amazighs de France et de monde, \u00e0 respecter leur identit\u00e9, leur langue et leur histoire, ainsi que leurs valeurs <em><strong>d\u00e9mocratiques,<\/strong><\/em> qui sont pourtant compl\u00e8tement compatibles avec les valeurs de la R\u00e9publique fran\u00e7aise. Soyons clairs qu\u2019en Afrique du Nord, berceau de l\u2019humanit\u00e9(6), il n\u2019y a pas d\u2019 \u00abArabes\u00bb, sinon des Amazighs, qui sont dans leur grande majorit\u00e9 amazighophones et\/ou darijaphones, et en minorit\u00e9, des francophones (Kabylie) et des hispanophones (\u00celes Canaries), et qu\u2019en France, l\u2019\u00e9crasante majorit\u00e9 des citoyen-ne-s issus des maghr\u00e9bins est incontestablement d\u2019origine amazighe (7).<\/p>\n<p>Dans l\u2019attente de vous pencher consciencieusement sur cette l\u00e9gitime requ\u00eate, nous vous prions d\u2019agr\u00e9er, Monsieur le Pr\u00e9sident, l\u2019expression de notre tr\u00e8s haute consid\u00e9ration.<\/p>\n<p style=\"text-align: center;\">Par<strong> Rachid RAHA, <\/strong>r\u00e9sident de l\u2019Assembl\u00e9e Mondiale Amazighe<\/p>\n<p><strong>Notes\u00a0:<\/strong><\/p>\n<p>(1) <a href=\"https:\/\/amadalamazigh.press.ma\/fr\/la-langue-maternelle-des-immigres-nest-pas-larabe\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/amadalamazigh.press.ma\/fr\/la-langue-maternelle-des-immigres-nest-pas-larabe\/<\/a><\/p>\n<p>(2) <a href=\"https:\/\/amamazigh.org\/2020\/11\/comment-la-france-et-leurope-pourraient-elles-lutter-efficacement-contre-lislamisme-radical\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/amamazigh.org\/2020\/11\/comment-la-france-et-leurope-pourraient-elles-lutter-efficacement-contre-lislamisme-radical\/<\/a><\/p>\n<p>(3) <a href=\"https:\/\/www.facebook.com\/142093689293727\/videos\/2490541604507247\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/142093689293727\/videos\/2490541604507247<\/a><\/p>\n<p>(4) <a href=\"http:\/\/www.sciencepo.ma\/2016\/12\/depassionner-et-depolitise-lecole-pr.html?m=1\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.sciencepo.ma\/2016\/12\/depassionner-et-depolitise-lecole-pr.html?m=1<\/a><\/p>\n<p>(5) <a href=\"http:\/\/amadalamazigh.press.ma\/fr\/rachid-raha-repond-a-la-banque-mondiale-et-insiste-sur-le-role-de-la-langue-maternelle-pour-sauver-la-petite-enfance-au-maroc\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/amadalamazigh.press.ma\/fr\/rachid-raha-repond-a-la-banque-mondiale-et-insiste-sur-le-role-de-la-langue-maternelle-pour-sauver-la-petite-enfance-au-maroc\/<\/a><\/p>\n<p>(6) <a href=\"https:\/\/www.youtube.com\/watch?v=Xnu6PIGn7EA\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.youtube.com\/watch?v=Xnu6PIGn7EA<\/a><\/p>\n<p>(7) <a href=\"http:\/\/amadalpresse.com\/RAHA\/Origines.html\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/amadalpresse.com\/RAHA\/Origines.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monsieur Emmanuel MACRON, Pr\u00e9sident de la R\u00e9publique fran\u00e7aise: Pourquoi vous acharnez \u00e0 \u00ab arabiser \u00bb et \u00e0 d\u00e9raciner les Amazighs de France? Monsieur le Pr\u00e9sident, Lors d\u2019une interview que vous venez de donner en direct au m\u00e9dia\u00a0Brut, ce samedi 5 d\u00e9cembre, en vous interrogeant sur le projet de loi sur l\u2019enseignement de la langue arabe, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3215,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-3213","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-maroc"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2020\/12\/MACRON_RAHA-2.jpg?fit=998%2C422&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p9uxE2-PP","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/3213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/comments?post=3213"}],"version-history":[{"count":2,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/3213\/revisions"}],"predecessor-version":[{"id":3217,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/3213\/revisions\/3217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media\/3215"}],"wp:attachment":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media?parent=3213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/categories?post=3213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/tags?post=3213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}