{"id":8175,"date":"2026-06-24T14:11:17","date_gmt":"2026-06-24T13:11:17","guid":{"rendered":"https:\/\/amadalamazigh.press.ma\/fr\/?p=8175"},"modified":"2026-06-24T14:11:17","modified_gmt":"2026-06-24T13:11:17","slug":"rabat-accueille-la-troisieme-edition-du-forum-des-dirigeants-postaux-pour-renforcer-les-chaines-logistiques-postales-au-service-du-commerce-electronique","status":"publish","type":"post","link":"https:\/\/amadalamazigh.press.ma\/fr\/rabat-accueille-la-troisieme-edition-du-forum-des-dirigeants-postaux-pour-renforcer-les-chaines-logistiques-postales-au-service-du-commerce-electronique\/","title":{"rendered":"Rabat accueille la troisi\u00e8me \u00e9dition du Forum des dirigeants postaux pour renforcer les cha\u00eenes logistiques postales au service du commerce \u00e9lectronique"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8176 alignright\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?resize=375%2C250&#038;ssl=1\" alt=\"\" width=\"375\" height=\"250\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?resize=375%2C250&amp;ssl=1 375w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?w=1599&amp;ssl=1 1599w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/>La ville de Rabat accueille, les 23 et 24 juin 2026, les travaux de la troisi\u00e8me \u00e9dition du Forum des dirigeants postaux, organis\u00e9 par le Groupe Barid Al-Maghrib en partenariat avec l\u2019Union Postale Universelle (UPU), sous le th\u00e8me : \u00ab<strong>Transformer les cha\u00eenes logistiques postales pour un avenir num\u00e9rique ax\u00e9 sur le commerce \u00e9lectronique<\/strong>\u00bb. Ce forum vise \u00e0 examiner les moyens d\u2019accompagner les mutations rapides que conna\u00eet le secteur postal dans un contexte marqu\u00e9 par la croissance continue du commerce \u00e9lectronique et de l\u2019\u00e9conomie num\u00e9rique.<\/p>\n<p>La s\u00e9ance d\u2019ouverture a \u00e9t\u00e9 marqu\u00e9e par la pr\u00e9sence de M. Ryad Mezzour, ministre de l\u2019Industrie et du Commerce, ainsi que de M. Amin Benjelloun Touimi, Directeur G\u00e9n\u00e9ral du Groupe Barid Al-Maghrib. Ont \u00e9galement pris part \u00e0 cette rencontre des repr\u00e9sentants du Bureau international de l\u2019UPU, les directeurs g\u00e9n\u00e9raux de 14 op\u00e9rateurs postaux participants, un repr\u00e9sentant de la Ligue des \u00c9tats arabes, ainsi que des repr\u00e9sentants des autorit\u00e9s de r\u00e9gulation postale et plusieurs personnalit\u00e9s nationales et internationales.<\/p>\n<p>L\u2019organisation de cette \u00e9dition au Royaume du Maroc s\u2019inscrit dans le cadre de <strong>la vision \u00e9clair\u00e9e de Sa Majest\u00e9 le Roi Mohammed VI, que Dieu L\u2019assiste<\/strong>, qui \u00e9rige la transformation num\u00e9rique et l\u2019int\u00e9gration \u00e9conomique en leviers essentiels du d\u00e9veloppement global. Ce forum s\u2019inscrit \u00e9galement dans la continuit\u00e9 des pr\u00e9c\u00e9dentes \u00e9ditions organis\u00e9es au Sultanat d\u2019Oman en 2024 et dans l\u2019\u00c9tat du Qatar en 2025, illustrant l\u2019importance du renforcement de la coop\u00e9ration et du partage d\u2019exp\u00e9riences dans le domaine des services postaux et logistiques.<\/p>\n<p>Les travaux du Forum abordent plusieurs enjeux strat\u00e9giques li\u00e9s \u00e0 l\u2019avenir du secteur, notamment la modernisation des cha\u00eenes logistiques et des r\u00e9seaux postaux, l\u2019int\u00e9gration des technologies avanc\u00e9es, de l\u2019intelligence artificielle et de l\u2019analyse des donn\u00e9es afin d\u2019am\u00e9liorer la performance op\u00e9rationnelle et la qualit\u00e9 des services, ainsi que le d\u00e9veloppement des partenariats entre les op\u00e9rateurs postaux et les diff\u00e9rents acteurs des \u00e9cosyst\u00e8mes logistiques et num\u00e9riques.<\/p>\n<p>Les participants examinent \u00e9galement les m\u00e9canismes de soutien au commerce \u00e9lectronique transfrontalier, les moyens de faciliter l\u2019acc\u00e8s des petites et moyennes entreprises aux march\u00e9s r\u00e9gionaux et internationaux, le d\u00e9veloppement des solutions du \u00ab dernier kilom\u00e8tre \u00bb, ainsi que les modalit\u00e9s de financement des projets de modernisation et de transformation num\u00e9rique visant \u00e0 renforcer la comp\u00e9titivit\u00e9 du secteur postal et sa capacit\u00e9 \u00e0 r\u00e9pondre aux exigences de l\u2019\u00e9conomie num\u00e9rique.<\/p>\n<p>Les travaux du Forum devraient s\u2019achever par l\u2019adoption d\u2019un ensemble de recommandations op\u00e9rationnelles et d\u2019une feuille de route de coop\u00e9ration pour la p\u00e9riode 2026-2027, destin\u00e9es \u00e0 soutenir le d\u00e9veloppement du commerce \u00e9lectronique, \u00e0 renforcer l\u2019int\u00e9gration logistique r\u00e9gionale et \u00e0 promouvoir un \u00e9cosyst\u00e8me postal plus r\u00e9silient, innovant et pr\u00e9par\u00e9 aux d\u00e9fis de l\u2019avenir.<\/p>\n<p>En marge de ses travaux, le Forum a \u00e9galement \u00e9t\u00e9 marqu\u00e9 par le lancement d\u2019une \u00e9mission philat\u00e9lique conjointe entre Poste Maroc et Mauripost, baptis\u00e9e \u00ab MoriPost \u00bb, illustrant la profondeur des relations de coop\u00e9ration et des \u00e9changes culturels entre les deux pays.<\/p>\n<p>Cette \u00e9mission se compose de deux timbres-poste. Le premier, repr\u00e9sentant la partie marocaine, met \u00e0 l\u2019honneur le ksar d\u2019A\u00eft Ben Haddou, situ\u00e9 dans la province de Ouarzazate et inscrit au patrimoine mondial de l\u2019UNESCO. Ce site embl\u00e9matique constitue l\u2019un des plus remarquables exemples de l\u2019architecture traditionnelle du sud du Maroc.<\/p>\n<p>Le second timbre est consacr\u00e9 \u00e0 la ville historique de Chinguetti, en Mauritanie, l\u2019une des plus anciennes cit\u00e9s culturelles et scientifiques du pays. Haut lieu du savoir et de la civilisation saharienne, Chinguetti symbolise un h\u00e9ritage commun et la richesse de la diversit\u00e9 culturelle qui caract\u00e9rise la r\u00e9gion.<\/p>\n<p>Cette \u00e9mission conjointe vient ainsi r\u00e9affirmer le r\u00f4le essentiel du timbre-poste dans la valorisation du patrimoine historique et culturel des peuples, tout en contribuant au renforcement des liens de communication, de rapprochement et de coop\u00e9ration entre les pays d\u2019Afrique du Nord.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8177 size-large\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/3.jpeg?resize=1024%2C682&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/3.jpeg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/3.jpeg?resize=375%2C250&amp;ssl=1 375w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/3.jpeg?resize=1536%2C1023&amp;ssl=1 1536w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/3.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8178 size-large\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/4.jpeg?resize=1024%2C682&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/4.jpeg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/4.jpeg?resize=375%2C250&amp;ssl=1 375w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/4.jpeg?resize=1536%2C1023&amp;ssl=1 1536w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/4.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8179 size-large\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/6.jpeg?resize=1024%2C682&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/6.jpeg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/6.jpeg?resize=375%2C250&amp;ssl=1 375w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/6.jpeg?resize=1536%2C1023&amp;ssl=1 1536w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/6.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8180 size-large\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/1.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" width=\"819\" height=\"1024\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/1.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/1.jpg?resize=200%2C250&amp;ssl=1 200w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/1.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8181 size-large\" src=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/2.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" width=\"819\" height=\"1024\" srcset=\"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/2.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/2.jpg?resize=200%2C250&amp;ssl=1 200w, https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/2.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ville de Rabat accueille, les 23 et 24 juin 2026, les travaux de la troisi\u00e8me \u00e9dition du Forum des dirigeants postaux, organis\u00e9 par le Groupe Barid Al-Maghrib en partenariat avec l\u2019Union Postale Universelle (UPU), sous le th\u00e8me : \u00abTransformer les cha\u00eenes logistiques postales pour un avenir num\u00e9rique ax\u00e9 sur le commerce \u00e9lectronique\u00bb. Ce forum &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8176,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-8175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maroc"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/amadalamazigh.press.ma\/fr\/wp-content\/uploads\/2026\/06\/5.jpeg?fit=1599%2C1067&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p9uxE2-27R","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/8175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/comments?post=8175"}],"version-history":[{"count":1,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/8175\/revisions"}],"predecessor-version":[{"id":8182,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/posts\/8175\/revisions\/8182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media\/8176"}],"wp:attachment":[{"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/media?parent=8175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/categories?post=8175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amadalamazigh.press.ma\/fr\/wp-json\/wp\/v2\/tags?post=8175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}